{"id":645,"date":"2025-02-08T09:19:42","date_gmt":"2025-02-08T09:19:42","guid":{"rendered":"https:\/\/knappenroth-zum-klaus.de\/?page_id=645"},"modified":"2025-02-19T12:07:43","modified_gmt":"2025-02-19T12:07:43","slug":"speisekarte","status":"publish","type":"page","link":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/","title":{"rendered":"Speisekarte"},"content":{"rendered":"<h1 style=\"text-align: center;\"><span style=\"font-family: 'arial black', sans-serif;\">Unsere Speisekarte<br \/>\n<\/span><\/h1>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Unsere Speisekarte<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_regular_price":[],"currency_symbol":[],"ngg_post_thumbnail":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-645","page","type-page","status-publish","hentry"],"post_slider_layout_featured_media_urls":{"thumbnail":"","post_slider_layout_landscape_large":"","post_slider_layout_portrait_large":"","post_slider_layout_square_large":"","post_slider_layout_landscape":"","post_slider_layout_portrait":"","post_slider_layout_square":"","full":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Speisekarte -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Speisekarte -\" \/>\n<meta property=\"og:description\" content=\"Unsere Speisekarte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T12:07:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/index.php\\\/speisekarte\\\/\",\"url\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/index.php\\\/speisekarte\\\/\",\"name\":\"Speisekarte -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/#website\"},\"datePublished\":\"2025-02-08T09:19:42+00:00\",\"dateModified\":\"2025-02-19T12:07:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/index.php\\\/speisekarte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/index.php\\\/speisekarte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/index.php\\\/speisekarte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Speisekarte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/#website\",\"url\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/knappenroth-zum-klaus.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Speisekarte -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/","og_locale":"de_DE","og_type":"article","og_title":"Speisekarte -","og_description":"Unsere Speisekarte","og_url":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/","article_modified_time":"2025-02-19T12:07:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/","url":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/","name":"Speisekarte -","isPartOf":{"@id":"https:\/\/knappenroth-zum-klaus.de\/#website"},"datePublished":"2025-02-08T09:19:42+00:00","dateModified":"2025-02-19T12:07:43+00:00","breadcrumb":{"@id":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/knappenroth-zum-klaus.de\/index.php\/speisekarte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/knappenroth-zum-klaus.de\/"},{"@type":"ListItem","position":2,"name":"Speisekarte"}]},{"@type":"WebSite","@id":"https:\/\/knappenroth-zum-klaus.de\/#website","url":"https:\/\/knappenroth-zum-klaus.de\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/knappenroth-zum-klaus.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/pages\/645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/comments?post=645"}],"version-history":[{"count":14,"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/pages\/645\/revisions"}],"predecessor-version":[{"id":711,"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/pages\/645\/revisions\/711"}],"wp:attachment":[{"href":"https:\/\/knappenroth-zum-klaus.de\/index.php\/wp-json\/wp\/v2\/media?parent=645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}